{"id":20136,"date":"2025-12-02T13:02:14","date_gmt":"2025-12-02T13:02:14","guid":{"rendered":"https://www.cecabank.es/eng/?p=20136"},"modified":"2025-12-02T13:02:16","modified_gmt":"2025-12-02T13:02:16","slug":"cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana","status":"publish","type":"post","link":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/","title":{"rendered":"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España"},"content":{"rendered":"\n<p><strong>Representantes del Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, junto a expertos procedentes de gestoras y distribuidores de primera línea, han analizado con Cecabank los avances y retos de la inversión colectiva en España</strong></p>\n\n\n\n<p><strong>Cecabank, como banco depositario líder en el mercado ibérico y entidad neutral e independiente, ejerce un papel clave en el ecosistema UCITS, evitando conflictos de interés y reforzando la confianza del inversor</strong></p>\n\n\n\n<p><strong>La entidad reafirma su compromiso con la industria de la inversión colectiva, impulsando nuevas operativas como el préstamo de valores para generar valor añadido y acompañar a las gestoras en su evolución</strong></p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-1024x681.jpg\" alt=\"\" class=\"wp-image-20137\" srcset=\"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-1024x681.jpg 1024w, https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-300x200.jpg 300w, https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-768x511.jpg 768w, https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-1536x1022.jpg 1536w, https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-2048x1362.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" /></figure>\n\n\n\n<p>Cecabank ha organizado una jornada conmemorativa para reflexionar sobre la evolución de la inversión colectiva en España, coincidiendo con el cuarenta aniversario de la Directiva UCITS, normativa europea que transformó la industria de fondos de inversión y la protección del inversor.</p>\n\n\n\n<p>La Directiva UCITS, aprobada en 1985 tras casi una década de negociaciones, sentó las bases para la creación de una industria sólida y armonizada en Europa. Hoy, los fondos UCITS superan los quince billones de euros en activos gestionados (veintitrés billones si se incluyen los fondos alternativos) y se han consolidado como una marca global sinónimo de transparencia, seguridad y prosperidad, tanto para inversores minoristas como institucionales. España, pionera en la armonización legislativa, aprobó en 1984 la primera Ley de Instituciones de Inversión Colectiva inspirada en esta normativa, anticipándose incluso a su entrada en vigor.</p>\n\n\n\n<p>Durante estas cuatro décadas, la Directiva se ha modificado en más de veinte ocasiones, adaptándose a los cambios regulatorios y tecnológicos, y la industria española ha evolucionado hasta convertirse en un pilar del ahorro financiero de las familias. Sobre estos avances y retos debatieron representantes del Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, junto a expertos procedentes de gestoras y distribuidores de primera línea, con Cecabank como banco depositario líder en el mercado ibérico.</p>\n\n\n\n<p>El encuentro comenzó con la bienvenida de <strong>Ainhoa Jáuregui, consejera delegada de Cecabank</strong>, quien destacó la relevancia histórica de la Directiva y el papel de Cecabank en la industria: “Miramos al pasado para reconocer nuestros orígenes, pero sobre todo analizamos el presente e imaginamos el futuro. Un futuro en el que Cecabank, como líder ibérico en depositaría, con más de 300.000 millones de euros depositados de medio centenar de gestoras, seguirá acompañando a la industria con rigor, innovación y compromiso, consolidando los fondos de inversión como un puerto seguro para el ahorro y la inversión”.</p>\n\n\n\n<p>A continuación, <strong>Jose Marcos, director general de Entidades de la CNMV</strong>, ofreció el discurso inaugural: “El sector español de IIC ha tenido un desarrollo muy sólido durante estos cuarenta años: el patrimonio se ha multiplicado por 42 veces, hasta 460 mil euros, y el número de cuentas de partícipes ha aumentado desde poco más de tres millones hasta más de 17,5 millones”. Jose Marcos opinó que “el sector puede afrontar su futuro con optimismo; se debe profundizar en el adecuado diseño de productos y comercializarlos correctamente y en interés de los inversores”. “Desde la CNMV trataremos de contribuir” añadió.</p>\n\n\n\n<p>La jornada incluyó la mesa redonda ‘Adaptación, innovación y confianza. Retos actuales de la inversión colectiva’, que contó con la participación de Ramón Cardil, director corporativo de Operaciones en Trea AM; Miguel López, director de Negocio en Ibercaja Gestión; Jesús Pinilla, director de Administración y Medios en Kutxabank Gestión; y Rafael Valera, consejero delegado en Buy&amp;Hold, bajo la moderación de Elisa Ricón, directora de Regulación de Cecabank.</p>\n\n\n\n<p>Posteriormente, Aurora Cuadros, directora corporativa de <em>Securities Services</em> de Cecabank, abordó el papel estratégico del depositario en la ponencia ‘Más que custodia: el rol estratégico del depositario’. Y Brenda Bol, Country Head de Cecabank en Luxemburgo, presentó el panel ‘Luxemburgo, un aliado para el crecimiento de la industria’.</p>\n\n\n\n<p>La jornada continuó con la mesa ‘Inversión colectiva y distribución: diagnóstico desde el terreno’, que reunió a Laura Comas, directora de Desarrollo y Transformación en CaixaBank Wealth Management; Ignacio Izquierdo, Regional Manager Iberia en Allfunds; Emilio Mejía, consejero delegado en Unicaja Asset Management; y Jesús Sánchez-Quiñones, consejero director general en Renta 4 Banco, moderada por Fernando Toledano, director de Desarrollo de Negocio de Cecabank.</p>\n\n\n\n<p><strong>Ángel Martínez-Aldama, presidente de INVERCO</strong>, analizó ‘Las instituciones de inversión colectiva y la composición del ahorro financiero de las familias españolas’, resaltando que: “El aniversario de la Directiva de UCITS nos recuerda algo fundamental: la confianza del inversor se construye sobre regulación sólida. Los fondos de inversión se han ganado ese prestigio gracias a estándares comunes, supervisión continua y transparencia reforzada. Si lo hacemos bien, y estoy seguro que así será, los fondos de inversión no solo seguirán creciendo, sino que se consolidarán como el instrumento central del ahorro de millones de personas y como un pilar clave del desarrollo económico español”.</p>\n\n\n\n<p>La clausura institucional corrió a cargo de <strong>Sergio Escobedo, subdirector general de Legislación Financiera del Ministerio de Economía, Comercio y Empresa</strong>, quien expuso las iniciativas europeas en materia de ahorro e inversión, incluyendo la cuenta de ahorro e inversión y la etiqueta <em>Finance Europe</em>, destacando: «Estamos aún lejos de los niveles de inversión minorista de otras jurisdicciones avanzadas. Y esto nos obliga a reflexionar sobre qué herramientas necesitamos para cerrar esa brecha. Ahí entran, precisamente, la cuenta de ahorro e inversión —como medio para incrementar la participación de los ciudadanos en los mercados financieros y, mediante ello, incrementar su renta disponible futura— y la etiqueta <em>Finance Europe</em> —que aspira a canalizar financiación de forma estructural y a largo plazo hacia las empresas del Espacio Económico Europeo—».</p>\n\n\n\n<p>Con esta jornada, Cecabank ha reafirmado su compromiso como banco depositario líder en el mercado ibérico, impulsando nuevas operativas como el préstamo de valores; liderando la transformación digital mediante soluciones innovadoras; apoyando la experiencia transfronteriza a través de sus sucursales en Luxemburgo y Lisboa y sus oficinas de representación en Londres y Fráncfort; y ejerciendo con rigor la función de depositario, rol que durante cuarenta años ha garantizado la custodia de los activos y la vigilancia de las gestoras.</p>\n","protected":false},"excerpt":{"rendered":"<p>Representantes del Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, junto a expertos procedentes de gestoras y distribuidores de primera línea, han analizado con Cecabank los avances y retos de la inversión colectiva en España Cecabank, como banco depositario líder en el mercado ibérico y entidad neutral e independiente, ejerce un papel clave en [&hellip;]</p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-20136","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https://yoast.com/product/yoast-seo-wordpress/ -->\n<title>Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España | Cecabank</title>\n<meta name=\"description\" content=\"El Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, gestoras, distribuidores y Cecabank han analizado los retos de la inversión colectiva.\" />\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/\" />\n<meta property=\"og:locale\" content=\"es_ES\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España | Cecabank\" />\n<meta property=\"og:description\" content=\"El Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, gestoras, distribuidores y Cecabank han analizado los retos de la inversión colectiva.\" />\n<meta property=\"og:url\" content=\"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/\" />\n<meta property=\"og:site_name\" content=\"Cecabank\" />\n<meta property=\"article:published_time\" content=\"2025-12-02T13:02:14+00:00\" />\n<meta property=\"article:modified_time\" content=\"2025-12-02T13:02:16+00:00\" />\n<meta property=\"og:image\" content=\"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg\" />\n\t<meta property=\"og:image:width\" content=\"2560\" />\n\t<meta property=\"og:image:height\" content=\"1703\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"María Jesús del Río Álvarez\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:image\" content=\"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg\" />\n<meta name=\"twitter:label1\" content=\"Escrito por\" />\n\t<meta name=\"twitter:data1\" content=\"María Jesús del Río Álvarez\" />\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/\"},\"author\":{\"name\":\"María Jesús del Río Álvarez\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/person\\/bcf7dc740970e36e32f0181a92ac21a1\"},\"headline\":\"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España\",\"datePublished\":\"2025-12-02T13:02:14+00:00\",\"dateModified\":\"2025-12-02T13:02:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/\"},\"wordCount\":1122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2025\\/12\\/40-anos-de-la-Directiva-UCITS_Cecabank-1024x681.jpg\",\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/\",\"url\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/\",\"name\":\"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España | Cecabank\",\"isPartOf\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2025\\/12\\/40-anos-de-la-Directiva-UCITS_Cecabank-1024x681.jpg\",\"datePublished\":\"2025-12-02T13:02:14+00:00\",\"dateModified\":\"2025-12-02T13:02:16+00:00\",\"description\":\"El Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, gestoras, distribuidores y Cecabank han analizado los retos de la inversión colectiva.\",\"breadcrumb\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#primaryimage\",\"url\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2025\\/12\\/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg\",\"contentUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2025\\/12\\/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/www.cecabank.es\\/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\/\\/www.cecabank.es\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#website\",\"url\":\"https:\\/\\/www.cecabank.es\\/\",\"name\":\"Cecabank\",\"description\":\"Banco mayorista\",\"publisher\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/www.cecabank.es\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#organization\",\"name\":\"Cecabank\",\"url\":\"https:\\/\\/www.cecabank.es\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2022\\/07\\/cropped-logo.png\",\"contentUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2022\\/07\\/cropped-logo.png\",\"width\":185,\"height\":31,\"caption\":\"Cecabank\"},\"image\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/logo\\/image\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/person\\/bcf7dc740970e36e32f0181a92ac21a1\",\"name\":\"María Jesús del Río Álvarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/1d8d4d2d9e6e3212bff1d441ba60b7e951ab8b5ebbab6f79133dc785a5aaceca?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/1d8d4d2d9e6e3212bff1d441ba60b7e951ab8b5ebbab6f79133dc785a5aaceca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/1d8d4d2d9e6e3212bff1d441ba60b7e951ab8b5ebbab6f79133dc785a5aaceca?s=96&d=mm&r=g\",\"caption\":\"María Jesús del Río Álvarez\"}}]}</script>\n<!-- / Yoast SEO plugin. -->","yoast_head_json":{"title":"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España | Cecabank","description":"El Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, gestoras, distribuidores y Cecabank han analizado los retos de la inversión colectiva.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/","og_locale":"es_ES","og_type":"article","og_title":"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España | Cecabank","og_description":"El Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, gestoras, distribuidores y Cecabank han analizado los retos de la inversión colectiva.","og_url":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/","og_site_name":"Cecabank","article_published_time":"2025-12-02T13:02:14+00:00","article_modified_time":"2025-12-02T13:02:16+00:00","og_image":[{"width":2560,"height":1703,"url":"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg","type":"image/jpeg"}],"author":"María Jesús del Río Álvarez","twitter_card":"summary_large_image","twitter_image":"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg","twitter_misc":{"Escrito por":"María Jesús del Río Álvarez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#article","isPartOf":{"@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/"},"author":{"name":"María Jesús del Río Álvarez","@id":"https://www.cecabank.es/eng/#/schema/person/bcf7dc740970e36e32f0181a92ac21a1"},"headline":"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España","datePublished":"2025-12-02T13:02:14+00:00","dateModified":"2025-12-02T13:02:16+00:00","mainEntityOfPage":{"@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/"},"wordCount":1122,"commentCount":0,"publisher":{"@id":"https://www.cecabank.es/eng/#organization"},"image":{"@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#primaryimage"},"thumbnailUrl":"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-1024x681.jpg","articleSection":["Notas de prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#respond"]}]},{"@type":"WebPage","@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/","url":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/","name":"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España | Cecabank","isPartOf":{"@id":"https://www.cecabank.es/eng/#website"},"primaryImageOfPage":{"@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#primaryimage"},"image":{"@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#primaryimage"},"thumbnailUrl":"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-1024x681.jpg","datePublished":"2025-12-02T13:02:14+00:00","dateModified":"2025-12-02T13:02:16+00:00","description":"El Ministerio de Economía, Comercio y Empresa, CNMV e INVERCO, gestoras, distribuidores y Cecabank han analizado los retos de la inversión colectiva.","breadcrumb":{"@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#primaryimage","url":"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg","contentUrl":"https://www.cecabank.es/eng/wp-content/uploads/2025/12/40-anos-de-la-Directiva-UCITS_Cecabank-scaled.jpg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https://www.cecabank.es/eng/cecabank-celebra-los-40-anos-de-la-directiva-ucits-y-analiza-el-futuro-de-la-inversion-colectiva-en-espana/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https://www.cecabank.es/eng/"},{"@type":"ListItem","position":2,"name":"Cecabank celebra los 40 años de la Directiva UCITS y analiza el futuro de la inversión colectiva en España"}]},{"@type":"WebSite","@id":"https://www.cecabank.es/eng/#website","url":"https://www.cecabank.es/eng/","name":"Cecabank","description":"Banco mayorista","publisher":{"@id":"https://www.cecabank.es/eng/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://www.cecabank.es/eng/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https://www.cecabank.es/eng/#organization","name":"Cecabank","url":"https://www.cecabank.es/eng/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https://www.cecabank.es/eng/#/schema/logo/image/","url":"https://www.cecabank.es/eng/wp-content/uploads/2022/07/cropped-logo.png","contentUrl":"https://www.cecabank.es/eng/wp-content/uploads/2022/07/cropped-logo.png","width":185,"height":31,"caption":"Cecabank"},"image":{"@id":"https://www.cecabank.es/eng/#/schema/logo/image/"}},{"@type":"Person","@id":"https://www.cecabank.es/eng/#/schema/person/bcf7dc740970e36e32f0181a92ac21a1","name":"María Jesús del Río Álvarez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https://secure.gravatar.com/avatar/1d8d4d2d9e6e3212bff1d441ba60b7e951ab8b5ebbab6f79133dc785a5aaceca?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/1d8d4d2d9e6e3212bff1d441ba60b7e951ab8b5ebbab6f79133dc785a5aaceca?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/1d8d4d2d9e6e3212bff1d441ba60b7e951ab8b5ebbab6f79133dc785a5aaceca?s=96&d=mm&r=g","caption":"María Jesús del Río Álvarez"}}]}},"_links":{"self":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts/20136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/users/4"}],"replies":[{"embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/comments?post=20136"}],"version-history":[{"count":4,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts/20136/revisions"}],"predecessor-version":[{"id":20145,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts/20136/revisions/20145"}],"wp:attachment":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/media?parent=20136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/categories?post=20136"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/tags?post=20136"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}