{"id":21082,"date":"2026-04-23T13:57:18","date_gmt":"2026-04-23T13:57:18","guid":{"rendered":"https://www.cecabank.es/eng/?p=21082"},"modified":"2026-05-12T09:57:41","modified_gmt":"2026-05-12T09:57:41","slug":"la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros","status":"publish","type":"post","link":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/","title":{"rendered":"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros"},"content":{"rendered":"\n<p><strong>La XII Jornada de Securities Services de Cecabank ha abordado cuestiones clave como el encaje regulatorio de las stablecoins, la tokenización de activos, la evolución del mercado de ETFs en Europa y el papel del capital riesgo en los mercados financieros</strong></p>\n\n\n\n<p><strong>Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro aportando la visión institucional sobre los desafíos de la industria y la evolución de los mercados</strong></p>\n\n\n\n<p><strong>Cecabank ha destacado como ejes estratégicos su actividad en custodia de criptoactivos, el avance hacia T+1, el lanzamiento de su agencia de securities lending y la apertura de su sucursal en Luxemburgo</strong></p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"695\" src=\"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-1024x695.jpeg\" alt=\"\" class=\"wp-image-21086\" srcset=\"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-1024x695.jpeg 1024w, https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-300x204.jpeg 300w, https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-768x522.jpeg 768w, https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-1536x1043.jpeg 1536w, https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-2048x1391.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" /></figure>\n\n\n\n<p>En un contexto marcado por la transformación estructural de los mercados financieros y por una creciente complejidad operativa, tecnológica y regulatoria, el sector de la postcontratación afronta un momento decisivo. El refuerzo de la resiliencia del sistema, el impulso a la innovación y la prestación de servicios cada vez más especializados sitúan al <em>postrading </em>como un pilar clave para la estabilidad y eficiencia de los mercados financieros. En este escenario, el diálogo entre los distintos actores de la industria resulta esencial para anticipar los retos y construir respuestas compartidas.</p>\n\n\n\n<p>Con este objetivo, Cecabank ha celebrado hoy su XII Jornada de <em>Securities Services</em>, bajo el lema “Construyendo futuro: resiliencia, innovación y servicio”. Un encuentro consolidado como foro de referencia del sector, que ha reunido a cerca de 300 representantes de más de 100 entidades de la industria de la postcontratación —entre entidades financieras, gestoras, reguladores, supervisores y empresas tecnológicas—, para analizar las tendencias que marcarán su evolución en los próximos años.</p>\n\n\n\n<p>La jornada ha tenido además el honor de contar en su apertura con la intervención de <strong>Soledad Núñez, subgobernadora del Banco de España</strong>, quien ha resaltado: “Nuestra intención es sentar las bases para permitir una transición progresiva en Europa hacia un ecosistema financiero más digital e integrado, asegurando que cualquier evolución hacia mercados de capitales tokenizados ocurre de forma ordenada”.</p>\n\n\n\n<p>La subgobernadora del Banco de España estuvo acompañada en la apertura por Iñaki Garay, director adjunto de Expansión, y por <strong>Ainhoa Jáuregui, consejera delegada de Cecabank</strong>, quien destacó: “En Cecabank afrontamos los retos de la industria desde una posición de fortaleza, apoyados en un modelo de negocio B2B sólido y en un firme compromiso con el sector. Somos el banco depositario líder y un referente en custodia en el mercado ibérico, respaldados por una estructura internacional con sucursales en Lisboa y Luxemburgo y una clara vocación de servicio a nuestros clientes”.</p>\n\n\n\n<p>La duodécima edición de la jornada ha estructurado su programa en torno a los principales vectores de transformación del sector, abordando la innovación tecnológica, la evolución regulatoria y el impacto de los nuevos modelos de inversión en las infraestructuras de mercado y los servicios de postcontratación.</p>\n\n\n\n<p>El programa se inició con una reflexión estratégica sobre el papel de las <em><strong>stablecoins </strong></em>en el ecosistema financiero, en un diálogo entre Ernesto Olmedo Pereira, Head of Strategy &amp; DeFi de Qivalis, y Aurora Cuadros, directora corporativa de Securities Services de Cecabank. El debate puso el foco en su encaje regulatorio y en las implicaciones potenciales para la eficiencia operativa y la gestión del riesgo, así como en los retos asociados a su integración progresiva en los flujos tradicionales del postrading.</p>\n\n\n\n<p>A continuación, Iñaki Varela, subdirector general de Medios de Kutxabank Investment; Marta López, Director Head Relationship Management Europe de Euroclear; y Daniel Zaplana, director de Operaciones de TREA Asset Management, ofrecieron su visión sobre el <strong><em>postrading </em>en el mercado español</strong>, con especial atención a la coordinación entre entidades, infraestructuras y gestoras. La sesión fue moderada por Óscar Mateos, director de Valores y Cuentas Corrientes de Securities Services de Cecabank.</p>\n\n\n\n<p>La siguiente mesa de debate se centró en analizar el avance de la <strong>tokenización </strong>como uno de los elementos clave en la evolución de los mercados financieros. Artur Callau, Corporate Innovation – Digital Assets de CaixaBank; Amparo García, General Manager de Securitize Europe; y Carlos Matilla, CEO de ioBuilders junto a Virginia Linares, directora de Coordinación y Control de Securities Services de Cecabank, repasaron los principales casos de uso y su impacto en los servicios de postcontratación.</p>\n\n\n\n<p>La jornada continuó con una ponencia a cargo de Silvia Senra, responsable de Distribución Digital de BlackRock Iberia, quien ofreció una visión experta sobre la evolución y tendencias de la industria de los <strong>ETFs </strong>en Europa. Durante su intervención analizó el crecimiento de este segmento, la innovación en producto, la transformación de los modelos de distribución y el papel creciente de los ETFs en las estrategias de inversión, tanto institucionales como minoristas.</p>\n\n\n\n<p>El encuentro concluyó con un análisis sobre el papel del <strong>capital riesgo</strong> como palanca de innovación y crecimiento en los mercados financieros, con la participación de Miguel Cacho, socio financiero de Arcano Capital; Borja de Luis, Managing Director y Head of Alternatives &amp; Infrastructure de Dunas Capital; y Carlos Conti, socio de Inveready. Moderada por Fernando Toledano, director de Desarrollo de Negocio de Cecabank, la sesión profundizó en su contribución a la evolución de las estrategias de inversión, la financiación de proyectos y la configuración de nuevos modelos de negocio dentro del ecosistema financiero.</p>\n\n\n\n<p>La clausura ha corrido a cargo de <strong>Carlos San Basilio, presidente de la Comisión Nacional del Mercado de Valores (CNMV)</strong>, que ha hecho un llamamiento para que todo el sector se prepare para pasar a T+1, ahora que llegan los momentos decisivos, y ha destacado: “En esta ocasión hay viento de cola y presión de las opiniones públicas para que avancemos hacia una verdadera integración de los mercados europeos”.</p>\n\n\n\n<p>El broche final lo ha puesto <strong>Aurora Cuadros, directora corporativa de <em>Securities Services</em> de Cecabank</strong>, que ha resaltado: “En los últimos meses, Cecabank ha impulsado una serie de hitos estratégicos orientados a reforzar el acompañamiento a sus clientes institucionales y anticiparse a la evolución del mercado. Entre ellos, la apertura de nuestra sucursal en Luxemburgo, la obtención de la licencia MiCA para la prestación de servicios de custodia de criptoactivos, el avance en la transición hacia T+1 en coordinación con el conjunto del mercado y la puesta en marcha de una agencia de <em>securities lending</em> para facilitar el préstamo de valores por parte de las instituciones de inversión colectiva”.</p>\n\n\n\n<p><strong>Cecabank, modelo B2B especializado que impulsa la resiliencia del sistema financiero</strong></p>\n\n\n\n<p>Desde hace más de una década, Cecabank desempeña un papel decisivo al proporcionar la infraestructura que contribuye de forma decisiva a la seguridad y estabilidad del sistema financiero a largo plazo. Este valor se apoya en un modelo B2B basado en la neutralidad, la solvencia operativa y la especialización, materializado en tres líneas de negocio: <em>Securities Services</em>, Pagos y Tesorería.</p>\n\n\n\n<p>En postcontratación, Cecabank protege el ahorro de cerca de diez millones de partícipes de forma rigurosa e independiente y alcanzó nuevamente este año cifras históricas en volúmenes de depositaría y custodia, consolidándose como líder en <em>Securites Services</em>.</p>\n\n\n\n<p>En el ámbito de la depositaría, Cecabank mantiene su posición como mayor depositario nacional independiente, prestando servicio a más de cincuenta gestoras de instituciones de inversión colectiva, fondos de pensiones, EPSV y entidades de capital riesgo. Con un patrimonio depositado de casi 300.000 millones de euros, distribuidos en cerca de mil vehículos de inversión, lo que evidencia la amplitud y diversidad de la actividad depositaria de la entidad.</p>\n\n\n\n<p>En servicios de custodia, la entidad continúa con un crecimiento sostenido. El volumen total de activos custodiados supera los 400.000 millones de euros, gestionados para más de 135 instituciones financieras y con acceso a más de 70 mercados internacionales, reflejo de una plataforma operativa robusta y con una marcada proyección global.</p>\n\n\n\n<p>Por esta trayectoria, el banco ha sido reconocido por décimo año consecutivo como mejor banco custodio de España, por la revista especializada <em>Global Banking and Finance Review</em>, lo que confirma su liderazgo en la industria y la confianza que los clientes depositan en su modelo de negocio independiente.</p>\n\n\n\n<p>La solidez del modelo se refleja además en una ratio CET1 superior al 52 % al cierre de 2025, una de las más elevadas del sistema financiero español, que respalda su capacidad para seguir invirtiendo en tecnología, resiliencia operativa e innovación.</p>\n","protected":false},"excerpt":{"rendered":"<p>La XII Jornada de Securities Services de Cecabank ha abordado cuestiones clave como el encaje regulatorio de las stablecoins, la tokenización de activos, la evolución del mercado de ETFs en Europa y el papel del capital riesgo en los mercados financieros Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de [&hellip;]</p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-21082","post","type-post","status-publish","format-standard","hentry","category-notas-de-prensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https://yoast.com/product/yoast-seo-wordpress/ -->\n<title>La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros | Cecabank</title>\n<meta name=\"description\" content=\"Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro.\" />\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/\" />\n<meta property=\"og:locale\" content=\"es_ES\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros | Cecabank\" />\n<meta property=\"og:description\" content=\"Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro.\" />\n<meta property=\"og:url\" content=\"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/\" />\n<meta property=\"og:site_name\" content=\"Cecabank\" />\n<meta property=\"article:published_time\" content=\"2026-04-23T13:57:18+00:00\" />\n<meta property=\"article:modified_time\" content=\"2026-05-12T09:57:41+00:00\" />\n<meta property=\"og:image\" content=\"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-scaled.jpeg\" />\n\t<meta property=\"og:image:width\" content=\"2560\" />\n\t<meta property=\"og:image:height\" content=\"1739\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Paula Gaspar\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:image\" content=\"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-scaled.jpeg\" />\n<meta name=\"twitter:label1\" content=\"Escrito por\" />\n\t<meta name=\"twitter:data1\" content=\"Paula Gaspar\" />\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" />\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/\"},\"author\":{\"name\":\"Paula Gaspar\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/person\\/6046d26758448f7a34b066abca28c3a4\"},\"headline\":\"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros\",\"datePublished\":\"2026-04-23T13:57:18+00:00\",\"dateModified\":\"2026-05-12T09:57:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/\"},\"wordCount\":1491,\"publisher\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2026\\/04\\/XII-Jornada-Securities-Services-1024x695.jpeg\",\"articleSection\":[\"Notas de prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/\",\"url\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/\",\"name\":\"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros | Cecabank\",\"isPartOf\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2026\\/04\\/XII-Jornada-Securities-Services-1024x695.jpeg\",\"datePublished\":\"2026-04-23T13:57:18+00:00\",\"dateModified\":\"2026-05-12T09:57:41+00:00\",\"description\":\"Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro.\",\"breadcrumb\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#primaryimage\",\"url\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2026\\/04\\/XII-Jornada-Securities-Services-scaled.jpeg\",\"contentUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2026\\/04\\/XII-Jornada-Securities-Services-scaled.jpeg\",\"width\":2560,\"height\":1739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/www.cecabank.es\\/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\/\\/www.cecabank.es\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#website\",\"url\":\"https:\\/\\/www.cecabank.es\\/\",\"name\":\"Cecabank\",\"description\":\"Banco mayorista\",\"publisher\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/www.cecabank.es\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#organization\",\"name\":\"Cecabank\",\"url\":\"https:\\/\\/www.cecabank.es\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2022\\/07\\/cropped-logo.png\",\"contentUrl\":\"https:\\/\\/www.cecabank.es\\/wp-content\\/uploads\\/2022\\/07\\/cropped-logo.png\",\"width\":185,\"height\":31,\"caption\":\"Cecabank\"},\"image\":{\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/logo\\/image\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/www.cecabank.es\\/#\\/schema\\/person\\/6046d26758448f7a34b066abca28c3a4\",\"name\":\"Paula Gaspar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/4dd35d80ad03bd19d163a882648488c42f2309ffefcb01c9466f8c60b0107033?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/4dd35d80ad03bd19d163a882648488c42f2309ffefcb01c9466f8c60b0107033?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/4dd35d80ad03bd19d163a882648488c42f2309ffefcb01c9466f8c60b0107033?s=96&d=mm&r=g\",\"caption\":\"Paula Gaspar\"}}]}</script>\n<!-- / Yoast SEO plugin. -->","yoast_head_json":{"title":"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros | Cecabank","description":"Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/","og_locale":"es_ES","og_type":"article","og_title":"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros | Cecabank","og_description":"Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro.","og_url":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/","og_site_name":"Cecabank","article_published_time":"2026-04-23T13:57:18+00:00","article_modified_time":"2026-05-12T09:57:41+00:00","og_image":[{"width":2560,"height":1739,"url":"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-scaled.jpeg","type":"image/jpeg"}],"author":"Paula Gaspar","twitter_card":"summary_large_image","twitter_image":"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-scaled.jpeg","twitter_misc":{"Escrito por":"Paula Gaspar","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#article","isPartOf":{"@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/"},"author":{"name":"Paula Gaspar","@id":"https://www.cecabank.es/eng/#/schema/person/6046d26758448f7a34b066abca28c3a4"},"headline":"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros","datePublished":"2026-04-23T13:57:18+00:00","dateModified":"2026-05-12T09:57:41+00:00","mainEntityOfPage":{"@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/"},"wordCount":1491,"publisher":{"@id":"https://www.cecabank.es/eng/#organization"},"image":{"@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#primaryimage"},"thumbnailUrl":"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-1024x695.jpeg","articleSection":["Notas de prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/","url":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/","name":"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros | Cecabank","isPartOf":{"@id":"https://www.cecabank.es/eng/#website"},"primaryImageOfPage":{"@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#primaryimage"},"image":{"@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#primaryimage"},"thumbnailUrl":"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-1024x695.jpeg","datePublished":"2026-04-23T13:57:18+00:00","dateModified":"2026-05-12T09:57:41+00:00","description":"Carlos San Basilio, presidente de la CNMV, y Soledad Núñez, subgobernadora del Banco de España, han participado en el encuentro.","breadcrumb":{"@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#primaryimage","url":"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-scaled.jpeg","contentUrl":"https://www.cecabank.es/eng/wp-content/uploads/2026/04/XII-Jornada-Securities-Services-scaled.jpeg","width":2560,"height":1739},{"@type":"BreadcrumbList","@id":"https://www.cecabank.es/eng/la-industria-del-postrading-clave-de-la-estabilidad-y-eficiencia-de-los-mercados-financieros/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https://www.cecabank.es/eng/"},{"@type":"ListItem","position":2,"name":"La industria del postrading, clave de la estabilidad y eficiencia de los mercados financieros"}]},{"@type":"WebSite","@id":"https://www.cecabank.es/eng/#website","url":"https://www.cecabank.es/eng/","name":"Cecabank","description":"Banco mayorista","publisher":{"@id":"https://www.cecabank.es/eng/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://www.cecabank.es/eng/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https://www.cecabank.es/eng/#organization","name":"Cecabank","url":"https://www.cecabank.es/eng/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https://www.cecabank.es/eng/#/schema/logo/image/","url":"https://www.cecabank.es/eng/wp-content/uploads/2022/07/cropped-logo.png","contentUrl":"https://www.cecabank.es/eng/wp-content/uploads/2022/07/cropped-logo.png","width":185,"height":31,"caption":"Cecabank"},"image":{"@id":"https://www.cecabank.es/eng/#/schema/logo/image/"}},{"@type":"Person","@id":"https://www.cecabank.es/eng/#/schema/person/6046d26758448f7a34b066abca28c3a4","name":"Paula Gaspar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https://secure.gravatar.com/avatar/4dd35d80ad03bd19d163a882648488c42f2309ffefcb01c9466f8c60b0107033?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/4dd35d80ad03bd19d163a882648488c42f2309ffefcb01c9466f8c60b0107033?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/4dd35d80ad03bd19d163a882648488c42f2309ffefcb01c9466f8c60b0107033?s=96&d=mm&r=g","caption":"Paula Gaspar"}}]}},"_links":{"self":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts/21082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/users/17"}],"replies":[{"embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/comments?post=21082"}],"version-history":[{"count":5,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts/21082/revisions"}],"predecessor-version":[{"id":21212,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/posts/21082/revisions/21212"}],"wp:attachment":[{"href":"https://www.cecabank.es/eng/wp-json/wp/v2/media?parent=21082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/categories?post=21082"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.cecabank.es/eng/wp-json/wp/v2/tags?post=21082"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}